{"id":17171,"date":"2025-06-06T11:37:05","date_gmt":"2025-06-06T14:37:05","guid":{"rendered":"https:\/\/fcs.tv\/?page_id=17171"},"modified":"2025-06-12T18:52:18","modified_gmt":"2025-06-12T21:52:18","slug":"relatos-ancestrales","status":"publish","type":"page","link":"https:\/\/fcs.tv\/en\/relatos-ancestrales\/","title":{"rendered":"Relatos Ancestrales"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row_content&#8221; content_placement=&#8221;middle&#8221; css_animation=&#8221;none&#8221; tablet_padding_left=&#8221;0&#8243; tablet_padding_right=&#8221;0&#8243; tablet_margin_left=&#8221;0&#8243; tablet_margin_right=&#8221;0&#8243; mobile_padding_left=&#8221;0&#8243; mobile_padding_right=&#8221;0&#8243; mobile_margin_left=&#8221;0&#8243; mobile_margin_right=&#8221;0&#8243;][vc_column css=&#8221;.vc_custom_1721048756342{margin-right: 40px !important;margin-left: 40px !important;}&#8221; tablet_padding_left=&#8221;0&#8243; tablet_padding_right=&#8221;0&#8243; tablet_margin_left=&#8221;0&#8243; tablet_margin_right=&#8221;0&#8243; mobile_padding_left=&#8221;0&#8243; mobile_padding_right=&#8221;0&#8243; mobile_margin_left=&#8221;0&#8243; mobile_margin_right=&#8221;0&#8243;][vc_column_text css=&#8221;&#8221;]<img class=\"aligncenter size-full wp-image-13856 imgportada\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Banner-de-Seccion-2.jpg\" alt=\"\" width=\"1820\" height=\"500\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221;][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1720718115150{margin-right: 0px !important;margin-left: 0px !important;}&#8221;]<div class=\"thegem-te-heading thegem-custom-6a03d9f4c3ca19388\" ><script type=\"text\/javascript\">(function() {function TheGemHeading() {this.animateClass = 'thegem-heading-animate';this.animatedClass = 'thegem-heading-animated';}TheGemHeading.prototype = {initialize: function () {let items =document.querySelectorAll('.'+this.animateClass);items.forEach((item)=>{if (this.isElementVisible(item)) {this.prepareAnimation(item);this.startAnimation(item);}});if ('ResizeObserver' in window) {const resizeObserver = new ResizeObserver((entries) => {entries.forEach((entry) => {this.prepareAnimation(entry.target);});});items.forEach((item) => {resizeObserver.observe(item);});}if ('IntersectionObserver' in window) {let intersectionObserver = new IntersectionObserver((entries)=>{entries.forEach((entry)=> {if (entry.isIntersecting) {this.startAnimation(entry.target);intersectionObserver.unobserve(entry.target);}});});items.forEach((item)=>{intersectionObserver.observe(item);this.prepareAnimation(item);});} else {items.forEach((item)=>{this.prepareAnimation(item);this.startAnimation(item);});}},isElementVisible: function (element) {let rect= element.getBoundingClientRect(),width= window.innerWidth || document.documentElement.clientWidth,height = window.innerHeight || document.documentElement.clientHeight,efp= (x, y) => document.elementFromPoint(x, y);if (rect.right < 0 || rect.bottom < 0 || rect.left > width || rect.top > height) return false;return (element.contains(efp(rect.left,rect.top)) ||element.contains(efp(rect.right, rect.top)) ||element.contains(efp(rect.right, rect.bottom)) ||element.contains(efp(rect.left,rect.bottom)));},startAnimation: function (element) {if (element && !element.classList.contains(this.animatedClass)) {element.classList.add(this.animatedClass);element.classList.remove(this.animateClass);element.dispatchEvent(new Event('theGemHeading.startAnimation', {bubbles: true}));}},prepareAnimation: function (element) {if (element\/* && !element.isPreparedAnimation*\/) {element.dispatchEvent(new Event('theGemHeading.prepareAnimation', {bubbles: true}));\/*element.isPreparedAnimation = true;*\/}}};window.theGemHeading = new TheGemHeading();document.addEventListener('DOMContentLoaded', function() {window.theGemHeading.initialize();});})();<\/script><h1 id=\"thegem-heading-6a03d9f4c3b6f\" class=\"thegem-heading thegem-custom-heading-6a03d9f4c3b6b5918 letters-scale-out thegem-heading-animate\" style=\"text-align: center;\" ><span class=\"colored thegem-heading-word\" style=\"color: #a07558;\"><span class=\"thegem-heading-letter\" style=\"animation-delay: 30ms\">R<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 60ms\">e<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 90ms\">l<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 120ms\">a<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 150ms\">t<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 180ms\">o<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 210ms\">s<\/span><\/span> <span class=\"colored thegem-heading-word\" style=\"color: #a07558;\"><span class=\"thegem-heading-letter\" style=\"animation-delay: 240ms\">A<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 270ms\">n<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 300ms\">c<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 330ms\">e<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 360ms\">s<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 390ms\">t<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 420ms\">r<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 450ms\">a<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 480ms\">l<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 510ms\">e<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 540ms\">s<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 570ms\">:<\/span><\/span> <span class=\"colored thegem-heading-word\" style=\"color: #a07558;\"><span class=\"thegem-heading-letter\" style=\"animation-delay: 600ms\">S<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 630ms\">a<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 660ms\">b<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 690ms\">e<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 720ms\">r<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 750ms\">e<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 780ms\">s<\/span><\/span> <span class=\"colored thegem-heading-word\" style=\"color: #a07558;\"><span class=\"thegem-heading-letter\" style=\"animation-delay: 810ms\">A<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 840ms\">n<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 870ms\">d<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 900ms\">i<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 930ms\">n<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 960ms\">o<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 990ms\">s<\/span><\/span> <span class=\"colored thegem-heading-word\" style=\"color: #a07558;\"><span class=\"thegem-heading-letter\" style=\"animation-delay: 1020ms\">p<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1050ms\">a<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1080ms\">r<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1110ms\">a<\/span><\/span> <span class=\"colored thegem-heading-word\" style=\"color: #a07558;\"><span class=\"thegem-heading-letter\" style=\"animation-delay: 1140ms\">u<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1170ms\">n<\/span><\/span> <span class=\"colored thegem-heading-word\" style=\"color: #a07558;\"><span class=\"thegem-heading-letter\" style=\"animation-delay: 1200ms\">F<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1230ms\">u<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1260ms\">t<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1290ms\">u<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1320ms\">r<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1350ms\">o<\/span><\/span> <span class=\"colored thegem-heading-word\" style=\"color: #a07558;\"><span class=\"thegem-heading-letter\" style=\"animation-delay: 1380ms\">S<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1410ms\">o<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1440ms\">s<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1470ms\">t<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1500ms\">e<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1530ms\">n<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1560ms\">i<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1590ms\">b<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1620ms\">l<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 1650ms\">e<\/span><\/span><\/h1><style type=\"text\/css\">#thegem-heading-6a03d9f4c3b6f {margin: 0;}#thegem-heading-6a03d9f4c3b6f {margin-left: auto; margin-right: auto;}#thegem-heading-6a03d9f4c3b6f > * {justify-content: center;}#thegem-heading-6a03d9f4c3b6f {font-size: 40px;}#thegem-heading-6a03d9f4c3b6f {line-height: 60px;}#thegem-heading-6a03d9f4c3b6f, #thegem-heading-6a03d9f4c3b6f .light {text-transform: none;}@media screen and (max-width: 1023px) and (min-width: 768px) {#thegem-heading-6a03d9f4c3b6f {font-size: 60px;}}@media screen and (max-width: 1023px) and (min-width: 768px) {#thegem-heading-6a03d9f4c3b6f {line-height: 70px;}}@media screen and (max-width: 767px) {#thegem-heading-6a03d9f4c3b6f {font-size: 45px;}}@media screen and (max-width: 767px) {#thegem-heading-6a03d9f4c3b6f {line-height: 50px;}}#thegem-heading-6a03d9f4c3b6f a:hover, #thegem-heading-6a03d9f4c3b6f a:hover span.colored {color: var(--thegem-to-menu-level1-color-hover, #00BCD4) !important;}<\/style><\/div><style>@media screen and (max-width: 1023px) {.thegem-heading.thegem-custom-heading-6a03d9f4c3b6b5918{display: block!important;}}@media screen and (max-width: 767px) {.thegem-heading.thegem-custom-heading-6a03d9f4c3b6b5918{display: block!important;}}@media screen and (max-width: 1023px) {.thegem-heading.thegem-custom-heading-6a03d9f4c3b6b5918{position: relative !important;}}@media screen and (max-width: 767px) {.thegem-heading.thegem-custom-heading-6a03d9f4c3b6b5918{position: relative !important;}}<\/style>[\/vc_column][vc_column width=&#8221;2\/3&#8243; css=&#8221;.vc_custom_1720718126297{margin-right: 0px !important;margin-left: 0px !important;}&#8221;][vc_column_text css=&#8221;&#8221;]Esta colecci\u00f3n re\u00fane relatos esenciales narrados por cultores y cultoras pertenecientes a los pueblos Lickanantay y Quechua. En palabras de Francisca Cort\u00e9s Solari, presidenta ejecutiva de Fundaci\u00f3n Caserta, estas historias &#8220;tienen que ver con la vida, las semillas, la agricultura y el universo&#8221;.<\/p>\n<p>Fruto de tres a\u00f1os dedicados intensamente a la investigaci\u00f3n, entrevistas y escritura en estrecha colaboraci\u00f3n con 21 cultores de Atacama La Grande y Alto Loa, se desarrollaron 21 c\u00e1psulas audiovisuales, inspiradas en la colecci\u00f3n de libros &#8220;Saberes Ancestrales y Cambio Clim\u00e1tico&#8221;.<\/p>\n<p>Cada c\u00e1psula es una ventana hacia la profunda cosmovisi\u00f3n andina, abordando temas cruciales para la conservaci\u00f3n y sostenibilidad ambiental tales como el manejo y cuidado del agua, la importancia del resguardo de las semillas, la apreciaci\u00f3n de los ciclos naturales y del denominado &#8220;tiempo andino&#8221;, as\u00ed como los usos y propiedades de sus hierbas medicinales, entre otros saberes fundamentales.<\/p>\n<p>En el contexto actual, marcado por la crisis clim\u00e1tica, este material audiovisual busca ofrecer una gu\u00eda llena de sabidur\u00eda ancestral no s\u00f3lo para Chile, sino para el mundo entero, proponiendo una nueva forma de relacionarnos con nuestro entorno natural y entre nosotros mismos. Se promueven valores como la reciprocidad, el respeto y el cuidado mutuo, que desaf\u00edan la perspectiva antropoc\u00e9ntrica para asumir una visi\u00f3n integral y equilibrada, reconociendo al ser humano como parte de un todo interconectado.<\/p>\n<p>Este legado busca inspirar un cambio profundo en nuestra manera de ver y habitar el mundo, aportando herramientas y ense\u00f1anzas pr\u00e1cticas desde la sabidur\u00eda ancestral, indispensables para enfrentar los desaf\u00edos globales que nos impone nuestro tiempo.[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1715872249716{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;background-color: #212128 !important;}&#8221; el_class=&#8221;gridcarousel&#8221;][vc_column css=&#8221;.vc_custom_1715872242318{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1748984984804{margin-top: 0px !important;margin-bottom: 0px !important;padding-bottom: 30px !important;}&#8221; css_animation=&#8221;fadeInUp&#8221;]<\/p>\n<h3 style=\"text-align: center;\"><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/der.png\" \/><span class=\"categoriatitulo\">Descubre las reservas<\/span><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/izq.png\" \/><\/h3>\n<p>[\/vc_column_text]<style>.portfolio.portfolio-grid#style-f36151e:not(.inited) .portfolio-item, .preloader#style-preloader-f36151e .portfolio-item { padding: calc(25px\/2) !important; }.portfolio.portfolio-grid#style-f36151e:not(.inited) .owl-stage, .preloader#style-preloader-f36151e .skeleton-posts.portfolio-row { margin: calc(-25px\/2); }.portfolio.portfolio-grid#style-f36151e .fullwidth-block:not(.no-paddings) { padding-left: 25px; padding-right: 25px; }.portfolio.portfolio-grid#style-f36151e.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(25px\/2) !important; margin: calc(-25px\/2); }@media (max-width: 991px) { .portfolio.portfolio-grid#style-f36151e:not(.inited) .portfolio-item, .preloader#style-preloader-f36151e .portfolio-item { padding: calc(20px\/2) !important; }.portfolio.portfolio-grid#style-f36151e:not(.inited) .owl-stage, .preloader#style-preloader-f36151e .skeleton-posts.portfolio-row { margin: calc(-20px\/2); }.portfolio.portfolio-grid#style-f36151e .fullwidth-block:not(.no-paddings) { padding-left: 20px; padding-right: 20px; }.portfolio.portfolio-grid#style-f36151e.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(20px\/2) !important; margin: calc(-20px\/2); }}@media (max-width: 767px) { .portfolio.portfolio-grid#style-f36151e:not(.inited) .portfolio-item, .preloader#style-preloader-f36151e .portfolio-item { padding: calc(10px\/2) !important; }.portfolio.portfolio-grid#style-f36151e:not(.inited) .owl-stage, .preloader#style-preloader-f36151e .skeleton-posts.portfolio-row { margin: calc(-10px\/2); }.portfolio.portfolio-grid#style-f36151e .fullwidth-block:not(.no-paddings) { padding-left: 10px; padding-right: 10px; }.portfolio.portfolio-grid#style-f36151e.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(10px\/2) !important; margin: calc(-10px\/2); }}.portfolio.portfolio-grid#style-f36151e .portfolio-item:not(.custom-ratio, .double-item) .image-inner:not(.empty) { aspect-ratio: 1.1 !important; height: auto; }.portfolio.portfolio-grid#style-f36151e .portfolio-item .caption .title span { letter-spacing: px !important; }.portfolio.portfolio-grid#style-f36151e .portfolio-item .caption .title span { white-space: initial; max-height: initial; display: -webkit-box; -webkit-line-clamp: 2; line-clamp: 2; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-f36151e .portfolio-item .caption .subtitle { max-height: initial !important; }.portfolio.portfolio-grid#style-f36151e .portfolio-item .caption .subtitle span { white-space: initial; display: -webkit-box; -webkit-line-clamp: 2; line-clamp: 2; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-f36151e .portfolio-item .caption .subtitle a, .portfolio.portfolio-grid#style-f36151e .portfolio-item .caption .subtitle p { white-space: initial; overflow: initial; }.portfolio.portfolio-grid#style-f36151e .extended-carousel-item .owl-nav .owl-prev div, .portfolio.portfolio-grid#style-f36151e .extended-carousel-item .owl-nav .owl-next div { color: #ffffff }.portfolio.portfolio-grid#style-f36151e .extended-carousel-item .owl-nav .owl-prev:hover div, .portfolio.portfolio-grid#style-f36151e .extended-carousel-item .owl-nav .owl-next:hover div { color: #ffffff }.portfolio.portfolio-grid#style-f36151e .extended-carousel-item .owl-nav .owl-prev div.position-on, .portfolio.portfolio-grid#style-f36151e .extended-carousel-item .owl-nav .owl-next div.position-on { background-color: #a07558 }.portfolio.portfolio-grid#style-f36151e .extended-carousel-item .owl-nav .owl-prev:hover div.position-on, .portfolio.portfolio-grid#style-f36151e .extended-carousel-item .owl-nav .owl-next:hover div.position-on { background-color: #a07558 }<\/style><style><\/style> <div id=\"style-preloader-f36151e\" class=\"preloader skeleton-carousel\"> <div class=\"skeleton\"> <div class=\"skeleton-posts portfolio-row\"> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17171 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17171 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17171 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17171 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17171 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17171 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17171 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17171 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17171 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17171 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17171 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17171 page type-page status-publish has-post-thumbnail\"> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-preloader-wrapper\"> <div class=\"portfolio portfolio-grid extended-portfolio-grid extended-portfolio-carousel extended-carousel-grid no-padding disable-isotope portfolio-style-justified portfolio-style-justified background-style-transparent hover-zooming-blur title-on-hover hover-elements-size-default version-alternative arrows-position-on caption-position-hover loading-animation item-animation-move-up hover-title columns-5 columns-tablet-3 columns-mobile-2 arrows-hover \" id=\"style-f36151e\" data-style-uid=\"f36151e\" data-portfolio-uid=\"grid_a6fb7a0\" data-columns-mobile=\"2\" data-columns-tablet=\"3\" data-columns-desktop=\"5\" data-margin-mobile=\"10\" data-margin-tablet=\"20\" data-margin-desktop=\"25\" data-hover=\"zooming-blur\" data-dots=\"\" data-arrows=\"1\" data-loop=\"\" data-sliding-animation=\"default\" data-autoscroll-speed=\"0\"> <div class=\"portfolio-row-outer \"> <div class=\"portfolio-row clearfix\"> <div class=\"portfolio-set\"> <div class=\"extended-carousel-wrap\"> <div class=\"extended-carousel-item owl-carousel owl-theme owl-loaded\"> <div class=\"owl-stage-outer\"> <div class=\"owl-stage\"> <div class=\"portfolio-item relatos-ancestrales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17105 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1749145806\"> <div class=\"wrap clearfix\"> <div class=\"image post-17105 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-1.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Relatos Ancestrales &#8211; Tiempo en que cantaban los p\u00e1jaros\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/vrFN07yizr0?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"Relatos Ancestrales &#8211; Tiempo en que cantaban los p\u00e1jaros\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item relatos-ancestrales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17110 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1749146000\"> <div class=\"wrap clearfix\"> <div class=\"image post-17110 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-2.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Relatos Ancestrales &#8211; Tiempo andino\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/YnllzeKdmVE?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"Relatos Ancestrales &#8211; Tiempo andino\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item relatos-ancestrales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17113 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1749146184\"> <div class=\"wrap clearfix\"> <div class=\"image post-17113 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-3.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Relatos Ancestrales &#8211; Pedir permiso a los cerros\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/VRKfdKl9x9E?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"Relatos Ancestrales &#8211; Pedir permiso a los cerros\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item relatos-ancestrales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17116 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1749146280\"> <div class=\"wrap clearfix\"> <div class=\"image post-17116 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-4.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Relatos Ancestrales &#8211; Escuchar a los Maikos\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/86nQOnvnS1g?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"Relatos Ancestrales &#8211; Escuchar a los Maikos\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item relatos-ancestrales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17119 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1749146380\"> <div class=\"wrap clearfix\"> <div class=\"image post-17119 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-5.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Relatos Ancestrales &#8211; Volver a lo elemental\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/d2yqEX-dkMA?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"Relatos Ancestrales &#8211; Volver a lo elemental\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item relatos-ancestrales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17122 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1749146525\"> <div class=\"wrap clearfix\"> <div class=\"image post-17122 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-6.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Relatos Ancestrales &#8211; El tesoro es la semilla\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/64Cb7RKMM_I?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"Relatos Ancestrales &#8211; El tesoro es la semilla\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item relatos-ancestrales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17125 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1749146784\"> <div class=\"wrap clearfix\"> <div class=\"image post-17125 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-7.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Relatos Ancestrales &#8211; Que me entierren con semillas\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/wxTJdSgmQlo?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"Relatos Ancestrales &#8211; Que me entierren con semillas\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item relatos-ancestrales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17128 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1749146906\"> <div class=\"wrap clearfix\"> <div class=\"image post-17128 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-8.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Relatos Ancestrales &#8211; La herencia es la semilla\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/lNXrecwxPDE?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"Relatos Ancestrales &#8211; La herencia es la semilla\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item relatos-ancestrales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17131 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1749147126\"> <div class=\"wrap clearfix\"> <div class=\"image post-17131 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-9.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Relatos Ancestrales &#8211; Un pu\u00f1ado de tierra\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/x9PL7-kym9M?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"Relatos Ancestrales &#8211; Un pu\u00f1ado de tierra\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item relatos-ancestrales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17134 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1749207078\"> <div class=\"wrap clearfix\"> <div class=\"image post-17134 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-10.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Relatos Ancestrales &#8211; Agua es vida\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/Kih8t1bz4vI?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"Relatos Ancestrales &#8211; Agua es vida\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item relatos-ancestrales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17137 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1749207210\"> <div class=\"wrap clearfix\"> <div class=\"image post-17137 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-11.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Relatos Ancestrales &#8211; Cantarle al agua\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/PQvoqM0IYWM?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"Relatos Ancestrales &#8211; Cantarle al agua\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item relatos-ancestrales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1749207442\"> <div class=\"wrap clearfix\"> <div class=\"image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-12.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Relatos Ancestrales &#8211; Lo comunitario\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/MU-t0yL4lKc?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"Relatos Ancestrales &#8211; Lo comunitario\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div><!-- .portflio-set --> <\/div><!-- .row--> <div class=\"slider-prev-icon position-on\"> <i class=\"default\"><\/i> <\/div> <div class=\"slider-next-icon position-on\"> <i class=\"default\"><\/i> <\/div> <\/div><!-- .full-width --> <\/div><!-- .portfolio--> <\/div><!-- .portfolio-preloader-wrapper-->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1738071668203{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;background-color: #212128 !important;}&#8221; el_class=&#8221;gridcarousel&#8221;][vc_column css=&#8221;.vc_custom_1715872242318{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1720662473187{margin-top: 0px !important;margin-bottom: 0px !important;padding-bottom: 30px !important;}&#8221; css_animation=&#8221;fadeInUp&#8221;]<\/p>\n<h3 style=\"text-align: center;\"><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/der.png\" \/><span class=\"categoriatitulo\">TE RECOMENDAMOS<\/span><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/izq.png\" \/><\/h3>\n<p>[\/vc_column_text]<style>.portfolio.portfolio-grid#style-13a7f3b:not(.inited) .portfolio-item, .preloader#style-preloader-13a7f3b .portfolio-item { padding: calc(25px\/2) !important; }.portfolio.portfolio-grid#style-13a7f3b:not(.inited) .owl-stage, .preloader#style-preloader-13a7f3b .skeleton-posts.portfolio-row { margin: calc(-25px\/2); }.portfolio.portfolio-grid#style-13a7f3b .fullwidth-block:not(.no-paddings) { padding-left: 25px; padding-right: 25px; }.portfolio.portfolio-grid#style-13a7f3b.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(25px\/2) !important; margin: calc(-25px\/2); }@media (max-width: 991px) { .portfolio.portfolio-grid#style-13a7f3b:not(.inited) .portfolio-item, .preloader#style-preloader-13a7f3b .portfolio-item { padding: calc(20px\/2) !important; }.portfolio.portfolio-grid#style-13a7f3b:not(.inited) .owl-stage, .preloader#style-preloader-13a7f3b .skeleton-posts.portfolio-row { margin: calc(-20px\/2); }.portfolio.portfolio-grid#style-13a7f3b .fullwidth-block:not(.no-paddings) { padding-left: 20px; padding-right: 20px; }.portfolio.portfolio-grid#style-13a7f3b.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(20px\/2) !important; margin: calc(-20px\/2); }}@media (max-width: 767px) { .portfolio.portfolio-grid#style-13a7f3b:not(.inited) .portfolio-item, .preloader#style-preloader-13a7f3b .portfolio-item { padding: calc(10px\/2) !important; }.portfolio.portfolio-grid#style-13a7f3b:not(.inited) .owl-stage, .preloader#style-preloader-13a7f3b .skeleton-posts.portfolio-row { margin: calc(-10px\/2); }.portfolio.portfolio-grid#style-13a7f3b .fullwidth-block:not(.no-paddings) { padding-left: 10px; padding-right: 10px; }.portfolio.portfolio-grid#style-13a7f3b.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(10px\/2) !important; margin: calc(-10px\/2); }}.portfolio.portfolio-grid#style-13a7f3b .portfolio-item:not(.custom-ratio, .double-item) .image-inner:not(.empty) { aspect-ratio: 1.1 !important; height: auto; }.portfolio.portfolio-grid#style-13a7f3b .portfolio-item .caption .title span { letter-spacing: px !important; }.portfolio.portfolio-grid#style-13a7f3b .portfolio-item .caption .title span { white-space: initial; max-height: initial; display: -webkit-box; -webkit-line-clamp: 2; line-clamp: 2; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-13a7f3b .portfolio-item .caption .subtitle { max-height: initial !important; }.portfolio.portfolio-grid#style-13a7f3b .portfolio-item .caption .subtitle span { white-space: initial; display: -webkit-box; -webkit-line-clamp: 2; line-clamp: 2; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-13a7f3b .portfolio-item .caption .subtitle a, .portfolio.portfolio-grid#style-13a7f3b .portfolio-item .caption .subtitle p { white-space: initial; overflow: initial; }.portfolio.portfolio-grid#style-13a7f3b .extended-carousel-item .owl-nav .owl-prev div, .portfolio.portfolio-grid#style-13a7f3b .extended-carousel-item .owl-nav .owl-next div { color: #ffffff }.portfolio.portfolio-grid#style-13a7f3b .extended-carousel-item .owl-nav .owl-prev:hover div, .portfolio.portfolio-grid#style-13a7f3b .extended-carousel-item .owl-nav .owl-next:hover div { color: #ffffff }.portfolio.portfolio-grid#style-13a7f3b .extended-carousel-item .owl-nav .owl-prev div.position-on, .portfolio.portfolio-grid#style-13a7f3b .extended-carousel-item .owl-nav .owl-next div.position-on { background-color: #a07558 }.portfolio.portfolio-grid#style-13a7f3b .extended-carousel-item .owl-nav .owl-prev:hover div.position-on, .portfolio.portfolio-grid#style-13a7f3b .extended-carousel-item .owl-nav .owl-next:hover div.position-on { background-color: #a07558 }<\/style><style><\/style> <div id=\"style-preloader-13a7f3b\" class=\"preloader skeleton-carousel\"> <div class=\"skeleton\"> <div class=\"skeleton-posts portfolio-row\"> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17140 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-preloader-wrapper\"> <div class=\"portfolio portfolio-grid extended-portfolio-grid extended-portfolio-carousel extended-carousel-grid no-padding disable-isotope portfolio-style-justified portfolio-style-justified background-style-transparent hover-zooming-blur title-on-hover hover-elements-size-default version-alternative arrows-position-on caption-position-hover loading-animation item-animation-move-up hover-title columns-5 columns-tablet-3 columns-mobile-2 arrows-hover \" id=\"style-13a7f3b\" data-style-uid=\"13a7f3b\" data-portfolio-uid=\"grid_a6fb7a0\" data-columns-mobile=\"2\" data-columns-tablet=\"3\" data-columns-desktop=\"5\" data-margin-mobile=\"10\" data-margin-tablet=\"20\" data-margin-desktop=\"25\" data-hover=\"zooming-blur\" data-dots=\"\" data-arrows=\"1\" data-loop=\"\" data-sliding-animation=\"default\" data-autoscroll-speed=\"0\"> <div class=\"portfolio-row-outer \"> <div class=\"portfolio-row clearfix\"> <div class=\"portfolio-set\"> <div class=\"extended-carousel-wrap\"> <div class=\"extended-carousel-item owl-carousel owl-theme owl-loaded\"> <div class=\"owl-stage-outer\"> <div class=\"owl-stage\"> <div class=\"portfolio-item nuevos-lanzamientos ambiental-listado proyectos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-13738 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1777148174\"> <div class=\"wrap clearfix\"> <div class=\"image post-13738 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/Portadas-Flamenco.jpg\" width=\"340\" height=\"300\" class=\"attachment-full\" alt=\"Flamencos Altoandinos\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/flamencos-altoandinos\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Flamencos Altoandinos\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos ambiental-listado documentales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18997 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1773250863\"> <div class=\"wrap clearfix\"> <div class=\"image post-18997 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2026\/03\/fondomarino.jpeg\" width=\"1600\" height=\"1412\" class=\"attachment-full\" alt=\"Expedici\u00f3n Fondo Marino en Bah\u00eda Melimoyu Documental\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/b3d3hczWPMU?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"Expedici\u00f3n Fondo Marino en Bah\u00eda Melimoyu Documental\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos ambiental-listado proyectos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18829 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1771490010\"> <div class=\"wrap clearfix\"> <div class=\"image post-18829 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2026\/02\/Caluga-ME-1.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Misi\u00f3n Elemental Evoluci\u00f3n natural Laboratorios vivos Conservaci\u00f3n efectiva Ciencia aplicada Educaci\u00f3n integral Aprendizaje experiencial Acci\u00f3n territorial Liderazgo ambiental Conexi\u00f3n local\u2013global Impacto sist\u00e9mico\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fcs.tv\/mision-elemental\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Misi\u00f3n Elemental Evoluci\u00f3n natural Laboratorios vivos Conservaci\u00f3n efectiva Ciencia aplicada Educaci\u00f3n integral Aprendizaje experiencial Acci\u00f3n territorial Liderazgo ambiental Conexi\u00f3n local\u2013global Impacto sist\u00e9mico\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos ambiental-listado conferenciasimg educacion-listado col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18767 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1768566361\"> <div class=\"wrap clearfix\"> <div class=\"image post-18767 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2026\/01\/seminarioprevencionincendios.jpeg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Seminario de Prevenci\u00f3n de Incendios Forestales &#8211; desde Reserva Elemental Likandes\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/seminario-de-prevencion-de-incendios-forestales\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Seminario de Prevenci\u00f3n de Incendios Forestales &#8211; desde Reserva Elemental Likandes\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos ambiental-listado documentales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18639 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1765808907\"> <div class=\"wrap clearfix\"> <div class=\"image post-18639 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/12\/Portada_FCSTV.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Para\u00edso Wild \u2013 Javier Mery documental naturaleza sur de chile Fotograf\u00eda fauna nativa Patagonia Regi\u00f3n de Ays\u00e9n\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fcs.tv\/paraiso-wild\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Para\u00edso Wild \u2013 Javier Mery documental naturaleza sur de chile Fotograf\u00eda fauna nativa Patagonia Regi\u00f3n de Ays\u00e9n\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item ambiental-listado proyectos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-13736 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1761422979\"> <div class=\"wrap clearfix\"> <div class=\"image post-13736 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/Portadas-TERRI.jpg\" width=\"340\" height=\"300\" class=\"attachment-full\" alt=\"TerritoriAR\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/territoriar\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"TerritoriAR\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos ambiental-listado documentales proyectos reservas-elementales col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17089 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1749124195\"> <div class=\"wrap clearfix\"> <div class=\"image post-17089 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-Seccion-Elemental-1.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Reserva Elemental Medio ambiente Mundo natural Ecosistema Entorno natural Biosfera H\u00e1bitat Campo (m\u00e1s rural) Paisaje Tierra virgen\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fcs.tv\/elemental-2\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Reserva Elemental Medio ambiente Mundo natural Ecosistema Entorno natural Biosfera H\u00e1bitat Campo (m\u00e1s rural) Paisaje Tierra virgen\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos ambiental-listado la-ruta-de-la-patagonia col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-16640 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1738167420\"> <div class=\"wrap clearfix\"> <div class=\"image post-16640 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/01\/Caluga-Expedicion.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Expedici\u00f3n fondo marino\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/expedicion-fondo-marino\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Expedici\u00f3n fondo marino\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos ambiental-listado proyectos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-13732 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1732565261\"> <div class=\"wrap clearfix\"> <div class=\"image post-13732 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/Portadas-Condores.jpg\" width=\"340\" height=\"300\" class=\"attachment-full\" alt=\"C\u00f3ndores\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/condores\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"C\u00f3ndores\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos ambiental-listado proyectos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-16113 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1728320203\"> <div class=\"wrap clearfix\"> <div class=\"image post-16113 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/10\/saberes.jpeg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Saberes Ancestrales y cambio Clim\u00e1tico\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/saberes-ancestrales\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Saberes Ancestrales y cambio Clim\u00e1tico\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item ambiental-listado proyectos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-14733 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1721933684\"> <div class=\"wrap clearfix\"> <div class=\"image post-14733 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/07\/Portadas-RE-Seccion-2.jpg\" width=\"340\" height=\"300\" class=\"attachment-full\" alt=\"Reservas Elementales\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/reservas-elementales\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Reservas Elementales\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item ambiental-listado la-ruta-de-la-patagonia proyectos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-13729 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1719345907\"> <div class=\"wrap clearfix\"> <div class=\"image post-13729 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/Portadas-BBI.jpg\" width=\"340\" height=\"300\" class=\"attachment-full\" alt=\"The Blue Boat Initiative reportaje documental cine ballena cetaceo mar oceano marino\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/the-blue-boat-initiative\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"The Blue Boat Initiative reportaje documental cine ballena cetaceo mar oceano marino\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div><!-- .portflio-set --> <\/div><!-- .row--> <div class=\"slider-prev-icon position-on\"> <i class=\"default\"><\/i> <\/div> <div class=\"slider-next-icon position-on\"> <i class=\"default\"><\/i> <\/div> <\/div><!-- .full-width --> <\/div><!-- .portfolio--> <\/div><!-- .portfolio-preloader-wrapper-->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1715872249716{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;background-color: #212128 !important;}&#8221; el_class=&#8221;gridcarousel&#8221;][vc_column css=&#8221;.vc_custom_1715872242318{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1720669469378{margin-top: 0px !important;margin-bottom: 0px !important;padding-bottom: 30px !important;}&#8221; css_animation=&#8221;fadeInUp&#8221;]<\/p>\n<h3 style=\"text-align: center;\"><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/der.png\" \/><span class=\"categoriatitulo\">RECURSOS DIGITALES RELACIONADOS<\/span><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/izq.png\" \/><\/h3>\n<p>[\/vc_column_text]<style>.portfolio.portfolio-grid#style-4f69aff:not(.inited) .portfolio-item, .preloader#style-preloader-4f69aff .portfolio-item { padding: calc(25px\/2) !important; }.portfolio.portfolio-grid#style-4f69aff:not(.inited) .owl-stage, .preloader#style-preloader-4f69aff .skeleton-posts.portfolio-row { margin: calc(-25px\/2); }.portfolio.portfolio-grid#style-4f69aff .fullwidth-block:not(.no-paddings) { padding-left: 25px; padding-right: 25px; }.portfolio.portfolio-grid#style-4f69aff.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(25px\/2) !important; margin: calc(-25px\/2); }@media (max-width: 991px) { .portfolio.portfolio-grid#style-4f69aff:not(.inited) .portfolio-item, .preloader#style-preloader-4f69aff .portfolio-item { padding: calc(20px\/2) !important; }.portfolio.portfolio-grid#style-4f69aff:not(.inited) .owl-stage, .preloader#style-preloader-4f69aff .skeleton-posts.portfolio-row { margin: calc(-20px\/2); }.portfolio.portfolio-grid#style-4f69aff .fullwidth-block:not(.no-paddings) { padding-left: 20px; padding-right: 20px; }.portfolio.portfolio-grid#style-4f69aff.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(20px\/2) !important; margin: calc(-20px\/2); }}@media (max-width: 767px) { .portfolio.portfolio-grid#style-4f69aff:not(.inited) .portfolio-item, .preloader#style-preloader-4f69aff .portfolio-item { padding: calc(10px\/2) !important; }.portfolio.portfolio-grid#style-4f69aff:not(.inited) .owl-stage, .preloader#style-preloader-4f69aff .skeleton-posts.portfolio-row { margin: calc(-10px\/2); }.portfolio.portfolio-grid#style-4f69aff .fullwidth-block:not(.no-paddings) { padding-left: 10px; padding-right: 10px; }.portfolio.portfolio-grid#style-4f69aff.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(10px\/2) !important; margin: calc(-10px\/2); }}.portfolio.portfolio-grid#style-4f69aff .portfolio-item:not(.custom-ratio, .double-item) .image-inner:not(.empty) { aspect-ratio: 1.1 !important; height: auto; }.portfolio.portfolio-grid#style-4f69aff .portfolio-item .caption .title span { letter-spacing: px !important; }.portfolio.portfolio-grid#style-4f69aff .portfolio-item .caption .title span { white-space: initial; max-height: initial; display: -webkit-box; -webkit-line-clamp: 4; line-clamp: 4; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-4f69aff .portfolio-item .caption .subtitle { max-height: initial !important; }.portfolio.portfolio-grid#style-4f69aff .portfolio-item .caption .subtitle span { white-space: initial; display: -webkit-box; -webkit-line-clamp: 2; line-clamp: 2; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-4f69aff .portfolio-item .caption .subtitle a, .portfolio.portfolio-grid#style-4f69aff .portfolio-item .caption .subtitle p { white-space: initial; overflow: initial; }.portfolio.portfolio-grid#style-4f69aff .extended-carousel-item .owl-nav .owl-prev div, .portfolio.portfolio-grid#style-4f69aff .extended-carousel-item .owl-nav .owl-next div { color: #ffffff }.portfolio.portfolio-grid#style-4f69aff .extended-carousel-item .owl-nav .owl-prev:hover div, .portfolio.portfolio-grid#style-4f69aff .extended-carousel-item .owl-nav .owl-next:hover div { color: #ffffff }.portfolio.portfolio-grid#style-4f69aff .extended-carousel-item .owl-nav .owl-prev div.position-on, .portfolio.portfolio-grid#style-4f69aff .extended-carousel-item .owl-nav .owl-next div.position-on { background-color: #a07558 }.portfolio.portfolio-grid#style-4f69aff .extended-carousel-item .owl-nav .owl-prev:hover div.position-on, .portfolio.portfolio-grid#style-4f69aff .extended-carousel-item .owl-nav .owl-next:hover div.position-on { background-color: #a07558 }<\/style><style><\/style> <div id=\"style-preloader-4f69aff\" class=\"preloader skeleton-carousel\"> <div class=\"skeleton\"> <div class=\"skeleton-posts portfolio-row\"> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-13729 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-13729 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-13729 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-13729 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-13729 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-13729 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-13729 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-preloader-wrapper\"> <div class=\"portfolio portfolio-grid extended-portfolio-grid extended-portfolio-carousel extended-carousel-grid no-padding disable-isotope portfolio-style-justified portfolio-style-justified background-style-transparent hover-zooming-blur title-on-hover hover-elements-size-default version-alternative arrows-position-on caption-position-hover loading-animation item-animation-move-up hover-title columns-5 columns-tablet-3 columns-mobile-2 arrows-hover \" id=\"style-4f69aff\" data-style-uid=\"4f69aff\" data-portfolio-uid=\"grid_a6fb7a0\" data-columns-mobile=\"2\" data-columns-tablet=\"3\" data-columns-desktop=\"5\" data-margin-mobile=\"10\" data-margin-tablet=\"20\" data-margin-desktop=\"25\" data-hover=\"zooming-blur\" data-dots=\"\" data-arrows=\"1\" data-loop=\"\" data-sliding-animation=\"default\" data-autoscroll-speed=\"0\"> <div class=\"portfolio-row-outer \"> <div class=\"portfolio-row clearfix\"> <div class=\"portfolio-set\"> <div class=\"extended-carousel-wrap\"> <div class=\"extended-carousel-item owl-carousel owl-theme owl-loaded\"> <div class=\"owl-stage-outer\"> <div class=\"owl-stage\"> <div class=\"portfolio-item biblioteca-ecosistemas-marinos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-15180 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1722514257\"> <div class=\"wrap clearfix\"> <div class=\"image post-15180 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/08\/Solucionesbasadas.jpg\" width=\"709\" height=\"625\" class=\"attachment-full\" alt=\"The Blue Boat Initiative &#8211; Soluciones basadas en la naturaleza\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fundacionmeri.cl\/theblueboatinitiative\/wp-content\/uploads\/2022\/04\/infograph-es.pdf\" target=\"_blank\" class=\"icon outer-link \" data-elementor-open-lightbox=\"no\" aria-label=\"The Blue Boat Initiative &#8211; Soluciones basadas en la naturaleza\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"title \"> <span class=\"title-h5 \"> The Blue Boat Initiative &#8211; Soluciones basadas en la naturaleza <\/span> <\/div> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item biblioteca-ecosistemas-marinos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-15178 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1722514116\"> <div class=\"wrap clearfix\"> <div class=\"image post-15178 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/08\/importancia_Ballena.jpg\" width=\"709\" height=\"625\" class=\"attachment-full\" alt=\"The Blue Boat Initiative &#8211; La importancia de la ballena azul chilena\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fundacionmeri.cl\/theblueboatinitiative\/wp-content\/uploads\/2022\/02\/BBi_infografias_espanol.pdf\" target=\"_blank\" class=\"icon outer-link \" data-elementor-open-lightbox=\"no\" aria-label=\"The Blue Boat Initiative &#8211; La importancia de la ballena azul chilena\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"title \"> <span class=\"title-h5 \"> The Blue Boat Initiative &#8211; La importancia de la ballena azul chilena <\/span> <\/div> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item biblioteca-ecosistemas-marinos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-15173 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1722513954\"> <div class=\"wrap clearfix\"> <div class=\"image post-15173 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/08\/Brochure_BBI.jpg\" width=\"709\" height=\"625\" class=\"attachment-full\" alt=\"The Blue Boat Initiative &#8211; Dossier\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fundacionmeri.cl\/theblueboatinitiative\/wp-content\/uploads\/2022\/02\/Dossier_ES_2022.pdf\" target=\"_blank\" class=\"icon outer-link \" data-elementor-open-lightbox=\"no\" aria-label=\"The Blue Boat Initiative &#8211; Dossier\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"title \"> <span class=\"title-h5 \"> The Blue Boat Initiative &#8211; Dossier <\/span> <\/div> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item biblioteca-ecosistemas-marinos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-3491 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1644257359\"> <div class=\"wrap clearfix\"> <div class=\"image post-3491 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2022\/02\/Agua-Patagonica.jpg\" width=\"709\" height=\"625\" class=\"attachment-full\" alt=\"Gu\u00eda did\u00e1ctica \u201cel agua patag\u00f3nica\u201d versi\u00f3n 1\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fundacionmeri.cl\/wp-content\/uploads\/2024\/07\/MERI-Guia-Dulceacuicola-I.pdf\" target=\"_blank\" class=\"icon outer-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Gu\u00eda did\u00e1ctica \u201cel agua patag\u00f3nica\u201d versi\u00f3n 1\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"title \"> <span class=\"title-h5 \"> Gu\u00eda did\u00e1ctica \u201cel agua patag\u00f3nica\u201d versi\u00f3n 1 <\/span> <\/div> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item biblioteca-ecosistemas-marinos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-3488 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1644256278\"> <div class=\"wrap clearfix\"> <div class=\"image post-3488 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2022\/02\/Cetaceos.jpg\" width=\"709\" height=\"625\" class=\"attachment-full\" alt=\"Gu\u00eda did\u00e1ctica cet\u00e1ceos Patagonia Norte\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fundacionmeri.cl\/wp-content\/uploads\/2024\/07\/MERI-Guia-Didactica-de-Cetaceos.pdf\" target=\"_blank\" class=\"icon outer-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Gu\u00eda did\u00e1ctica cet\u00e1ceos Patagonia Norte\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"title \"> <span class=\"title-h5 \"> Gu\u00eda did\u00e1ctica cet\u00e1ceos Patagonia Norte <\/span> <\/div> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item biblioteca-ecosistemas-marinos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-3484 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1644254219\"> <div class=\"wrap clearfix\"> <div class=\"image post-3484 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2022\/02\/Bailahuen.jpg\" width=\"709\" height=\"625\" class=\"attachment-full\" alt=\"Cuento &#8220;Bailahu\u00e9n, la voz de las ballenas del sur&#8221;\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fundacionmeri.cl\/wp-content\/uploads\/2020\/09\/Bailahuen_ESP-EN.pdf\" target=\"_blank\" class=\"icon outer-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Cuento &#8220;Bailahu\u00e9n, la voz de las ballenas del sur&#8221;\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"title \"> <span class=\"title-h5 \"> Cuento &#8220;Bailahu\u00e9n, la voz de las ballenas del sur&#8221; <\/span> <\/div> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item biblioteca-ecosistemas-marinos col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-3482 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1644253816\"> <div class=\"wrap clearfix\"> <div class=\"image post-3482 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2022\/02\/Aguas_Patagonicas.jpg\" width=\"709\" height=\"625\" class=\"attachment-full\" alt=\"Gu\u00eda did\u00e1ctica aguas patag\u00f3nicas, de la cordillera al mar\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fundacionmeri.cl\/wp-content\/uploads\/2020\/09\/GDA_espanol.pdf\" target=\"_blank\" class=\"icon outer-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Gu\u00eda did\u00e1ctica aguas patag\u00f3nicas, de la cordillera al mar\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"title \"> <span class=\"title-h5 \"> Gu\u00eda did\u00e1ctica aguas patag\u00f3nicas, de la cordillera al mar <\/span> <\/div> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div><!-- .portflio-set --> <\/div><!-- .row--> <div class=\"slider-prev-icon position-on\"> <i class=\"default\"><\/i> <\/div> <div class=\"slider-next-icon position-on\"> <i class=\"default\"><\/i> <\/div> <\/div><!-- .full-width --> <\/div><!-- .portfolio--> <\/div><!-- .portfolio-preloader-wrapper-->[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content&#8221; content_placement=&#8221;middle&#8221; css_animation=&#8221;none&#8221; tablet_padding_left=&#8221;0&#8243; tablet_padding_right=&#8221;0&#8243; tablet_margin_left=&#8221;0&#8243; tablet_margin_right=&#8221;0&#8243; mobile_padding_left=&#8221;0&#8243; mobile_padding_right=&#8221;0&#8243; mobile_margin_left=&#8221;0&#8243; mobile_margin_right=&#8221;0&#8243;][vc_column css=&#8221;.vc_custom_1721048756342{margin-right: 40px !important;margin-left: 40px !important;}&#8221; tablet_padding_left=&#8221;0&#8243; tablet_padding_right=&#8221;0&#8243; tablet_margin_left=&#8221;0&#8243;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17172,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-17171","page","type-page","status-publish","has-post-thumbnail"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["es","en"],"languages":{"es":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/pages\/17171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/comments?post=17171"}],"version-history":[{"count":4,"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/pages\/17171\/revisions"}],"predecessor-version":[{"id":17351,"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/pages\/17171\/revisions\/17351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/media\/17172"}],"wp:attachment":[{"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/media?parent=17171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}