{"id":18191,"date":"2025-08-13T15:30:59","date_gmt":"2025-08-13T18:30:59","guid":{"rendered":"https:\/\/fcs.tv\/?page_id=18191"},"modified":"2025-08-13T15:44:31","modified_gmt":"2025-08-13T18:44:31","slug":"novopangea-chile-2020","status":"publish","type":"page","link":"https:\/\/fcs.tv\/en\/novopangea-chile-2020\/","title":{"rendered":"NovoPangea Chile 2020"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row_content&#8221; content_placement=&#8221;middle&#8221; css_animation=&#8221;none&#8221; tablet_padding_left=&#8221;0&#8243; tablet_padding_right=&#8221;0&#8243; tablet_margin_left=&#8221;0&#8243; tablet_margin_right=&#8221;0&#8243; mobile_padding_left=&#8221;0&#8243; mobile_padding_right=&#8221;0&#8243; mobile_margin_left=&#8221;0&#8243; mobile_margin_right=&#8221;0&#8243;][vc_column css=&#8221;.vc_custom_1721048756342{margin-right: 40px !important;margin-left: 40px !important;}&#8221; tablet_padding_left=&#8221;0&#8243; tablet_padding_right=&#8221;0&#8243; tablet_margin_left=&#8221;0&#8243; tablet_margin_right=&#8221;0&#8243; mobile_padding_left=&#8221;0&#8243; mobile_padding_right=&#8221;0&#8243; mobile_margin_left=&#8221;0&#8243; mobile_margin_right=&#8221;0&#8243;][vc_column_text css=&#8221;&#8221;]<img class=\"aligncenter size-full wp-image-13856 imgportada\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Banner-Seccion.jpg\" alt=\"\" width=\"1820\" height=\"500\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221;][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1720718115150{margin-right: 0px !important;margin-left: 0px !important;}&#8221;]<div class=\"thegem-te-heading thegem-custom-6a03d9b0653b79448\" ><script type=\"text\/javascript\">(function() {function TheGemHeading() {this.animateClass = 'thegem-heading-animate';this.animatedClass = 'thegem-heading-animated';}TheGemHeading.prototype = {initialize: function () {let items =document.querySelectorAll('.'+this.animateClass);items.forEach((item)=>{if (this.isElementVisible(item)) {this.prepareAnimation(item);this.startAnimation(item);}});if ('ResizeObserver' in window) {const resizeObserver = new ResizeObserver((entries) => {entries.forEach((entry) => {this.prepareAnimation(entry.target);});});items.forEach((item) => {resizeObserver.observe(item);});}if ('IntersectionObserver' in window) {let intersectionObserver = new IntersectionObserver((entries)=>{entries.forEach((entry)=> {if (entry.isIntersecting) {this.startAnimation(entry.target);intersectionObserver.unobserve(entry.target);}});});items.forEach((item)=>{intersectionObserver.observe(item);this.prepareAnimation(item);});} else {items.forEach((item)=>{this.prepareAnimation(item);this.startAnimation(item);});}},isElementVisible: function (element) {let rect= element.getBoundingClientRect(),width= window.innerWidth || document.documentElement.clientWidth,height = window.innerHeight || document.documentElement.clientHeight,efp= (x, y) => document.elementFromPoint(x, y);if (rect.right < 0 || rect.bottom < 0 || rect.left > width || rect.top > height) return false;return (element.contains(efp(rect.left,rect.top)) ||element.contains(efp(rect.right, rect.top)) ||element.contains(efp(rect.right, rect.bottom)) ||element.contains(efp(rect.left,rect.bottom)));},startAnimation: function (element) {if (element && !element.classList.contains(this.animatedClass)) {element.classList.add(this.animatedClass);element.classList.remove(this.animateClass);element.dispatchEvent(new Event('theGemHeading.startAnimation', {bubbles: true}));}},prepareAnimation: function (element) {if (element\/* && !element.isPreparedAnimation*\/) {element.dispatchEvent(new Event('theGemHeading.prepareAnimation', {bubbles: true}));\/*element.isPreparedAnimation = true;*\/}}};window.theGemHeading = new TheGemHeading();document.addEventListener('DOMContentLoaded', function() {window.theGemHeading.initialize();});})();<\/script><h1 id=\"thegem-heading-6a03d9b0652ce\" class=\"thegem-heading thegem-custom-heading-6a03d9b0652cb1330 letters-scale-out thegem-heading-animate\" style=\"text-align: center;\" ><span class=\"colored thegem-heading-word\" style=\"color: #a07558;\"><span class=\"thegem-heading-letter\" style=\"animation-delay: 30ms\">N<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 60ms\">o<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 90ms\">v<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 120ms\">o<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 150ms\">P<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 180ms\">a<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 210ms\">n<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 240ms\">g<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 270ms\">e<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 300ms\">a<\/span><\/span> <span class=\"colored thegem-heading-word\" style=\"color: #a07558;\"><span class=\"thegem-heading-letter\" style=\"animation-delay: 330ms\">C<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 360ms\">h<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 390ms\">i<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 420ms\">l<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 450ms\">e<\/span><\/span> <span class=\"colored thegem-heading-word\" style=\"color: #a07558;\"><span class=\"thegem-heading-letter\" style=\"animation-delay: 480ms\">2<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 510ms\">0<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 540ms\">2<\/span><span class=\"thegem-heading-letter\" style=\"animation-delay: 570ms\">0<\/span><\/span><\/h1><style type=\"text\/css\">#thegem-heading-6a03d9b0652ce {margin: 0;}#thegem-heading-6a03d9b0652ce {margin-left: auto; margin-right: auto;}#thegem-heading-6a03d9b0652ce > * {justify-content: center;}#thegem-heading-6a03d9b0652ce {font-size: 35px;}#thegem-heading-6a03d9b0652ce {line-height: 50px;}#thegem-heading-6a03d9b0652ce, #thegem-heading-6a03d9b0652ce .light {text-transform: none;}@media screen and (max-width: 1023px) and (min-width: 768px) {#thegem-heading-6a03d9b0652ce {font-size: 30px;}}@media screen and (max-width: 1023px) and (min-width: 768px) {#thegem-heading-6a03d9b0652ce {line-height: 40px;}}@media screen and (max-width: 767px) {#thegem-heading-6a03d9b0652ce {font-size: 45px;}}@media screen and (max-width: 767px) {#thegem-heading-6a03d9b0652ce {line-height: 50px;}}#thegem-heading-6a03d9b0652ce a:hover, #thegem-heading-6a03d9b0652ce a:hover span.colored {color: var(--thegem-to-menu-level1-color-hover, #00BCD4) !important;}<\/style><\/div><style>@media screen and (max-width: 1023px) {.thegem-heading.thegem-custom-heading-6a03d9b0652cb1330{display: block!important;}}@media screen and (max-width: 767px) {.thegem-heading.thegem-custom-heading-6a03d9b0652cb1330{display: block!important;}}@media screen and (max-width: 1023px) {.thegem-heading.thegem-custom-heading-6a03d9b0652cb1330{position: relative !important;}}@media screen and (max-width: 767px) {.thegem-heading.thegem-custom-heading-6a03d9b0652cb1330{position: relative !important;}}<\/style>[\/vc_column][vc_column width=&#8221;2\/3&#8243; css=&#8221;.vc_custom_1720718126297{margin-right: 0px !important;margin-left: 0px !important;}&#8221;][vc_column_text css=&#8221;&#8221;]Primera Conferencia sobre Cambio Clim\u00e1tico, Evidencia Cient\u00edfica y Pol\u00edticas P\u00fablicas para Am\u00e9rica Latina y el Caribe.[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1715872249716{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;background-color: #212128 !important;}&#8221; el_class=&#8221;gridcarousel&#8221;][vc_column css=&#8221;.vc_custom_1715872242318{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1755109577874{margin-top: 0px !important;margin-bottom: 0px !important;padding-bottom: 30px !important;}&#8221; css_animation=&#8221;fadeInUp&#8221;]<\/p>\n<h3 style=\"text-align: center;\"><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/der.png\" \/><span class=\"categoriatitulo\">D\u00eda 1<\/span><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/izq.png\" \/><\/h3>\n<p>[\/vc_column_text]<style>.portfolio.portfolio-grid#style-430d3e5:not(.inited) .portfolio-item, .preloader#style-preloader-430d3e5 .portfolio-item { padding: calc(25px\/2) !important; }.portfolio.portfolio-grid#style-430d3e5:not(.inited) .owl-stage, .preloader#style-preloader-430d3e5 .skeleton-posts.portfolio-row { margin: calc(-25px\/2); }.portfolio.portfolio-grid#style-430d3e5 .fullwidth-block:not(.no-paddings) { padding-left: 25px; padding-right: 25px; }.portfolio.portfolio-grid#style-430d3e5.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(25px\/2) !important; margin: calc(-25px\/2); }@media (max-width: 991px) { .portfolio.portfolio-grid#style-430d3e5:not(.inited) .portfolio-item, .preloader#style-preloader-430d3e5 .portfolio-item { padding: calc(20px\/2) !important; }.portfolio.portfolio-grid#style-430d3e5:not(.inited) .owl-stage, .preloader#style-preloader-430d3e5 .skeleton-posts.portfolio-row { margin: calc(-20px\/2); }.portfolio.portfolio-grid#style-430d3e5 .fullwidth-block:not(.no-paddings) { padding-left: 20px; padding-right: 20px; }.portfolio.portfolio-grid#style-430d3e5.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(20px\/2) !important; margin: calc(-20px\/2); }}@media (max-width: 767px) { .portfolio.portfolio-grid#style-430d3e5:not(.inited) .portfolio-item, .preloader#style-preloader-430d3e5 .portfolio-item { padding: calc(10px\/2) !important; }.portfolio.portfolio-grid#style-430d3e5:not(.inited) .owl-stage, .preloader#style-preloader-430d3e5 .skeleton-posts.portfolio-row { margin: calc(-10px\/2); }.portfolio.portfolio-grid#style-430d3e5 .fullwidth-block:not(.no-paddings) { padding-left: 10px; padding-right: 10px; }.portfolio.portfolio-grid#style-430d3e5.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(10px\/2) !important; margin: calc(-10px\/2); }}.portfolio.portfolio-grid#style-430d3e5 .portfolio-item:not(.custom-ratio, .double-item) .image-inner:not(.empty) { aspect-ratio: 1.1 !important; height: auto; }.portfolio.portfolio-grid#style-430d3e5 .portfolio-item .caption .title span { letter-spacing: px !important; }.portfolio.portfolio-grid#style-430d3e5 .portfolio-item .caption .title span { white-space: initial; max-height: initial; display: -webkit-box; -webkit-line-clamp: 2; line-clamp: 2; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-430d3e5 .portfolio-item .caption .subtitle { max-height: initial !important; }.portfolio.portfolio-grid#style-430d3e5 .portfolio-item .caption .subtitle span { white-space: initial; display: -webkit-box; -webkit-line-clamp: 2; line-clamp: 2; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-430d3e5 .portfolio-item .caption .subtitle a, .portfolio.portfolio-grid#style-430d3e5 .portfolio-item .caption .subtitle p { white-space: initial; overflow: initial; }.portfolio.portfolio-grid#style-430d3e5 .extended-carousel-item .owl-nav .owl-prev div, .portfolio.portfolio-grid#style-430d3e5 .extended-carousel-item .owl-nav .owl-next div { color: #ffffff }.portfolio.portfolio-grid#style-430d3e5 .extended-carousel-item .owl-nav .owl-prev:hover div, .portfolio.portfolio-grid#style-430d3e5 .extended-carousel-item .owl-nav .owl-next:hover div { color: #ffffff }.portfolio.portfolio-grid#style-430d3e5 .extended-carousel-item .owl-nav .owl-prev div.position-on, .portfolio.portfolio-grid#style-430d3e5 .extended-carousel-item .owl-nav .owl-next div.position-on { background-color: #a07558 }.portfolio.portfolio-grid#style-430d3e5 .extended-carousel-item .owl-nav .owl-prev:hover div.position-on, .portfolio.portfolio-grid#style-430d3e5 .extended-carousel-item .owl-nav .owl-next:hover div.position-on { background-color: #a07558 }<\/style><style><\/style> <div id=\"style-preloader-430d3e5\" class=\"preloader skeleton-carousel\"> <div class=\"skeleton\"> <div class=\"skeleton-posts portfolio-row\"> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18191 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18191 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18191 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18191 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18191 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18191 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18191 page type-page status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18191 page type-page status-publish has-post-thumbnail\"> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-preloader-wrapper\"> <div class=\"portfolio portfolio-grid extended-portfolio-grid extended-portfolio-carousel extended-carousel-grid no-padding disable-isotope portfolio-style-justified portfolio-style-justified background-style-transparent hover-zooming-blur title-on-hover hover-elements-size-default version-alternative arrows-position-on caption-position-hover loading-animation item-animation-move-up hover-title columns-5 columns-tablet-3 columns-mobile-2 arrows-hover \" id=\"style-430d3e5\" data-style-uid=\"430d3e5\" data-portfolio-uid=\"grid_a6fb7a0\" data-columns-mobile=\"2\" data-columns-tablet=\"3\" data-columns-desktop=\"5\" data-margin-mobile=\"10\" data-margin-tablet=\"20\" data-margin-desktop=\"25\" data-hover=\"zooming-blur\" data-dots=\"\" data-arrows=\"1\" data-loop=\"\" data-sliding-animation=\"default\" data-autoscroll-speed=\"0\"> <div class=\"portfolio-row-outer \"> <div class=\"portfolio-row clearfix\"> <div class=\"portfolio-set\"> <div class=\"extended-carousel-wrap\"> <div class=\"extended-carousel-item owl-carousel owl-theme owl-loaded\"> <div class=\"owl-stage-outer\"> <div class=\"owl-stage\"> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-1 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18155 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755087701\"> <div class=\"wrap clearfix\"> <div class=\"image post-18155 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-02-2.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea 2020 Chile Bienvenida d\u00eda 1\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/kIk5yZPw9m4?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea 2020 Chile Bienvenida d\u00eda 1\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-1 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18162 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755088095\"> <div class=\"wrap clearfix\"> <div class=\"image post-18162 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-03.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea Chile 2020 &#8211; El rol del IPCC en Am\u00e9rica Latina y el Caribe para la toma de decisiones en Adaptaci\u00f3n\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/Us5IdpXcOTA?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea Chile 2020 &#8211; El rol del IPCC en Am\u00e9rica Latina y el Caribe para la toma de decisiones en Adaptaci\u00f3n\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-1 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18165 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755088677\"> <div class=\"wrap clearfix\"> <div class=\"image post-18165 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-04.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea Chile 2020 &#8211; Informe especial del IPCC sobre el oc\u00e9ano y la cri\u00f3sfera en un clima cambiante\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/i2pY2j3u8Hg?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea Chile 2020 &#8211; Informe especial del IPCC sobre el oc\u00e9ano y la cri\u00f3sfera en un clima cambiante\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-1 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18168 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755089117\"> <div class=\"wrap clearfix\"> <div class=\"image post-18168 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-05.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea Chile 2020 &#8211; Panel 1 Oc\u00e9anos: desaf\u00edos y soluciones\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/-hedl6SiayQ?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea Chile 2020 &#8211; Panel 1 Oc\u00e9anos: desaf\u00edos y soluciones\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-1 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18172 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755089979\"> <div class=\"wrap clearfix\"> <div class=\"image post-18172 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-06.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea Chile 2020 &#8211; Informe especial del IPCC sobre el Cambio Clim\u00e1tico y la Tierra\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/-TkgCJJuSe8?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea Chile 2020 &#8211; Informe especial del IPCC sobre el Cambio Clim\u00e1tico y la Tierra\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-1 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18175 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755090443\"> <div class=\"wrap clearfix\"> <div class=\"image post-18175 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-07.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea Chile 2020 &#8211; Panel 2 Agricultura Sustentable y Seguridad Alimentaria\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/yCIJoVENmEA?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea Chile 2020 &#8211; Panel 2 Agricultura Sustentable y Seguridad Alimentaria\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-1 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18178 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755091371\"> <div class=\"wrap clearfix\"> <div class=\"image post-18178 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-08.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea Chile 2020 &#8211; Informe IPCC Calentamiento Global de 1 5\u00b0\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/RylJfy4bC8Y?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea Chile 2020 &#8211; Informe IPCC Calentamiento Global de 1 5\u00b0\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-1 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18182 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755091572\"> <div class=\"wrap clearfix\"> <div class=\"image post-18182 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-09.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea Chile 2020 &#8211; Panel 3 Modelo de desarrollo sustentable ODS y Cambio Clim\u00e1tico\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/qb_rY26ysuc?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea Chile 2020 &#8211; Panel 3 Modelo de desarrollo sustentable ODS y Cambio Clim\u00e1tico\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div><!-- .portflio-set --> <\/div><!-- .row--> <div class=\"slider-prev-icon position-on\"> <i class=\"default\"><\/i> <\/div> <div class=\"slider-next-icon position-on\"> <i class=\"default\"><\/i> <\/div> <\/div><!-- .full-width --> <\/div><!-- .portfolio--> <\/div><!-- .portfolio-preloader-wrapper-->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1715872249716{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;background-color: #212128 !important;}&#8221; el_class=&#8221;gridcarousel&#8221;][vc_column css=&#8221;.vc_custom_1715872242318{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1755109750050{margin-top: 0px !important;margin-bottom: 0px !important;padding-bottom: 30px !important;}&#8221; css_animation=&#8221;fadeInUp&#8221;]<\/p>\n<h3 style=\"text-align: center;\"><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/der.png\" \/><span class=\"categoriatitulo\">D\u00eda 2<\/span><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/izq.png\" \/><\/h3>\n<p>[\/vc_column_text]<style>.portfolio.portfolio-grid#style-bf5ff8e:not(.inited) .portfolio-item, .preloader#style-preloader-bf5ff8e .portfolio-item { padding: calc(25px\/2) !important; }.portfolio.portfolio-grid#style-bf5ff8e:not(.inited) .owl-stage, .preloader#style-preloader-bf5ff8e .skeleton-posts.portfolio-row { margin: calc(-25px\/2); }.portfolio.portfolio-grid#style-bf5ff8e .fullwidth-block:not(.no-paddings) { padding-left: 25px; padding-right: 25px; }.portfolio.portfolio-grid#style-bf5ff8e.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(25px\/2) !important; margin: calc(-25px\/2); }@media (max-width: 991px) { .portfolio.portfolio-grid#style-bf5ff8e:not(.inited) .portfolio-item, .preloader#style-preloader-bf5ff8e .portfolio-item { padding: calc(20px\/2) !important; }.portfolio.portfolio-grid#style-bf5ff8e:not(.inited) .owl-stage, .preloader#style-preloader-bf5ff8e .skeleton-posts.portfolio-row { margin: calc(-20px\/2); }.portfolio.portfolio-grid#style-bf5ff8e .fullwidth-block:not(.no-paddings) { padding-left: 20px; padding-right: 20px; }.portfolio.portfolio-grid#style-bf5ff8e.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(20px\/2) !important; margin: calc(-20px\/2); }}@media (max-width: 767px) { .portfolio.portfolio-grid#style-bf5ff8e:not(.inited) .portfolio-item, .preloader#style-preloader-bf5ff8e .portfolio-item { padding: calc(10px\/2) !important; }.portfolio.portfolio-grid#style-bf5ff8e:not(.inited) .owl-stage, .preloader#style-preloader-bf5ff8e .skeleton-posts.portfolio-row { margin: calc(-10px\/2); }.portfolio.portfolio-grid#style-bf5ff8e .fullwidth-block:not(.no-paddings) { padding-left: 10px; padding-right: 10px; }.portfolio.portfolio-grid#style-bf5ff8e.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(10px\/2) !important; margin: calc(-10px\/2); }}.portfolio.portfolio-grid#style-bf5ff8e .portfolio-item:not(.custom-ratio, .double-item) .image-inner:not(.empty) { aspect-ratio: 1.1 !important; height: auto; }.portfolio.portfolio-grid#style-bf5ff8e .portfolio-item .caption .title span { letter-spacing: px !important; }.portfolio.portfolio-grid#style-bf5ff8e .portfolio-item .caption .title span { white-space: initial; max-height: initial; display: -webkit-box; -webkit-line-clamp: 2; line-clamp: 2; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-bf5ff8e .portfolio-item .caption .subtitle { max-height: initial !important; }.portfolio.portfolio-grid#style-bf5ff8e .portfolio-item .caption .subtitle span { white-space: initial; display: -webkit-box; -webkit-line-clamp: 2; line-clamp: 2; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-bf5ff8e .portfolio-item .caption .subtitle a, .portfolio.portfolio-grid#style-bf5ff8e .portfolio-item .caption .subtitle p { white-space: initial; overflow: initial; }.portfolio.portfolio-grid#style-bf5ff8e .extended-carousel-item .owl-nav .owl-prev div, .portfolio.portfolio-grid#style-bf5ff8e .extended-carousel-item .owl-nav .owl-next div { color: #ffffff }.portfolio.portfolio-grid#style-bf5ff8e .extended-carousel-item .owl-nav .owl-prev:hover div, .portfolio.portfolio-grid#style-bf5ff8e .extended-carousel-item .owl-nav .owl-next:hover div { color: #ffffff }.portfolio.portfolio-grid#style-bf5ff8e .extended-carousel-item .owl-nav .owl-prev div.position-on, .portfolio.portfolio-grid#style-bf5ff8e .extended-carousel-item .owl-nav .owl-next div.position-on { background-color: #a07558 }.portfolio.portfolio-grid#style-bf5ff8e .extended-carousel-item .owl-nav .owl-prev:hover div.position-on, .portfolio.portfolio-grid#style-bf5ff8e .extended-carousel-item .owl-nav .owl-next:hover div.position-on { background-color: #a07558 }<\/style><style><\/style> <div id=\"style-preloader-bf5ff8e\" class=\"preloader skeleton-carousel\"> <div class=\"skeleton\"> <div class=\"skeleton-posts portfolio-row\"> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18182 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18182 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18182 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18182 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18182 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18182 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18182 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-preloader-wrapper\"> <div class=\"portfolio portfolio-grid extended-portfolio-grid extended-portfolio-carousel extended-carousel-grid no-padding disable-isotope portfolio-style-justified portfolio-style-justified background-style-transparent hover-zooming-blur title-on-hover hover-elements-size-default version-alternative arrows-position-on caption-position-hover loading-animation item-animation-move-up hover-title columns-5 columns-tablet-3 columns-mobile-2 arrows-hover \" id=\"style-bf5ff8e\" data-style-uid=\"bf5ff8e\" data-portfolio-uid=\"grid_a6fb7a0\" data-columns-mobile=\"2\" data-columns-tablet=\"3\" data-columns-desktop=\"5\" data-margin-mobile=\"10\" data-margin-tablet=\"20\" data-margin-desktop=\"25\" data-hover=\"zooming-blur\" data-dots=\"\" data-arrows=\"1\" data-loop=\"\" data-sliding-animation=\"default\" data-autoscroll-speed=\"0\"> <div class=\"portfolio-row-outer \"> <div class=\"portfolio-row clearfix\"> <div class=\"portfolio-set\"> <div class=\"extended-carousel-wrap\"> <div class=\"extended-carousel-item owl-carousel owl-theme owl-loaded\"> <div class=\"owl-stage-outer\"> <div class=\"owl-stage\"> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-2 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18185 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755091864\"> <div class=\"wrap clearfix\"> <div class=\"image post-18185 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-10.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea Chile 2020 &#8211; Bienvenida d\u00eda 2\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/IGcLzpGkwrQ?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea Chile 2020 &#8211; Bienvenida d\u00eda 2\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-2 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18188 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755092062\"> <div class=\"wrap clearfix\"> <div class=\"image post-18188 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-11.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea Chile 2020 &#8211; El rol del IPCC en Am\u00e9rica Latina y el Caribe para la toma de decisiones en Mitigaci\u00f3n\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/Zdd4HSao7wE?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea Chile 2020 &#8211; El rol del IPCC en Am\u00e9rica Latina y el Caribe para la toma de decisiones en Mitigaci\u00f3n\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-2 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18201 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755101240\"> <div class=\"wrap clearfix\"> <div class=\"image post-18201 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-12.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea 2020 Chile &#8211; Resultados del IPCC: Gobernanza Clim\u00e1tica\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/DjOdP9SVjHU?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea 2020 Chile &#8211; Resultados del IPCC: Gobernanza Clim\u00e1tica\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-2 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18204 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755101435\"> <div class=\"wrap clearfix\"> <div class=\"image post-18204 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-13.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea Chile 2020 &#8211; Panel 4 Gobernanza y Cambio Clim\u00e1tico\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/K2aWQA5sV7w?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea Chile 2020 &#8211; Panel 4 Gobernanza y Cambio Clim\u00e1tico\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-2 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18208 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755101675\"> <div class=\"wrap clearfix\"> <div class=\"image post-18208 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-14.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea Chile 2020 &#8211; Informe IPCC Oc\u00e9anos y Cri\u00f3sfera Cap\u00edtulo de zonas de altas monta\u00f1as\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/HQnF339u6Lk?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea Chile 2020 &#8211; Informe IPCC Oc\u00e9anos y Cri\u00f3sfera Cap\u00edtulo de zonas de altas monta\u00f1as\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-2 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18211 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755101795\"> <div class=\"wrap clearfix\"> <div class=\"image post-18211 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-15.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea Chile 2020 &#8211; Panel 5 Naturaleza y Sociedad: reconciliando las necesidades por agua\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/WcMNLfD5ks0?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea Chile 2020 &#8211; Panel 5 Naturaleza y Sociedad: reconciliando las necesidades por agua\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item novopangea-chile-2020 novopangea-chile-2020-dia-2 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1755101947\"> <div class=\"wrap clearfix\"> <div class=\"image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/08\/Portada-16.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"NovoPangea Chile 2020 &#8211; Panel 6 Modelos de Conservaci\u00f3n Efectiva\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/\/www.youtube.com\/embed\/TOiFi4DdVjE?autoplay=1\" target=\"_self\" class=\"icon youtube video\" data-fancybox=\"thegem-portfolio\" data-elementor-open-lightbox=\"no\" aria-label=\"NovoPangea Chile 2020 &#8211; Panel 6 Modelos de Conservaci\u00f3n Efectiva\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div><!-- .portflio-set --> <\/div><!-- .row--> <div class=\"slider-prev-icon position-on\"> <i class=\"default\"><\/i> <\/div> <div class=\"slider-next-icon position-on\"> <i class=\"default\"><\/i> <\/div> <\/div><!-- .full-width --> <\/div><!-- .portfolio--> <\/div><!-- .portfolio-preloader-wrapper-->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1715872249716{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;background-color: #212128 !important;}&#8221; el_id=&#8221;loultimo&#8221; el_class=&#8221;gridcarousel&#8221;][vc_column css=&#8221;.vc_custom_1715872242318{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1720662473187{margin-top: 0px !important;margin-bottom: 0px !important;padding-bottom: 30px !important;}&#8221; css_animation=&#8221;fadeInUp&#8221;]<\/p>\n<h3 style=\"text-align: center;\"><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/der.png\" \/><span class=\"categoriatitulo\">TE RECOMENDAMOS<\/span><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/izq.png\" \/><\/h3>\n<p>[\/vc_column_text]<style>.portfolio.portfolio-grid#style-43f9542:not(.inited) .portfolio-item, .preloader#style-preloader-43f9542 .portfolio-item { padding: calc(25px\/2) !important; }.portfolio.portfolio-grid#style-43f9542:not(.inited) .owl-stage, .preloader#style-preloader-43f9542 .skeleton-posts.portfolio-row { margin: calc(-25px\/2); }.portfolio.portfolio-grid#style-43f9542 .fullwidth-block:not(.no-paddings) { padding-left: 25px; padding-right: 25px; }.portfolio.portfolio-grid#style-43f9542.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(25px\/2) !important; margin: calc(-25px\/2); }@media (max-width: 991px) { .portfolio.portfolio-grid#style-43f9542:not(.inited) .portfolio-item, .preloader#style-preloader-43f9542 .portfolio-item { padding: calc(20px\/2) !important; }.portfolio.portfolio-grid#style-43f9542:not(.inited) .owl-stage, .preloader#style-preloader-43f9542 .skeleton-posts.portfolio-row { margin: calc(-20px\/2); }.portfolio.portfolio-grid#style-43f9542 .fullwidth-block:not(.no-paddings) { padding-left: 20px; padding-right: 20px; }.portfolio.portfolio-grid#style-43f9542.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(20px\/2) !important; margin: calc(-20px\/2); }}@media (max-width: 767px) { .portfolio.portfolio-grid#style-43f9542:not(.inited) .portfolio-item, .preloader#style-preloader-43f9542 .portfolio-item { padding: calc(10px\/2) !important; }.portfolio.portfolio-grid#style-43f9542:not(.inited) .owl-stage, .preloader#style-preloader-43f9542 .skeleton-posts.portfolio-row { margin: calc(-10px\/2); }.portfolio.portfolio-grid#style-43f9542 .fullwidth-block:not(.no-paddings) { padding-left: 10px; padding-right: 10px; }.portfolio.portfolio-grid#style-43f9542.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(10px\/2) !important; margin: calc(-10px\/2); }}.portfolio.portfolio-grid#style-43f9542 .portfolio-item:not(.custom-ratio, .double-item) .image-inner:not(.empty) { aspect-ratio: 1.1 !important; height: auto; }.portfolio.portfolio-grid#style-43f9542 .portfolio-item .caption .title span { letter-spacing: px !important; }.portfolio.portfolio-grid#style-43f9542 .portfolio-item .caption .title span { white-space: initial; max-height: initial; display: -webkit-box; -webkit-line-clamp: 2; line-clamp: 2; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-43f9542 .portfolio-item .caption .subtitle { max-height: initial !important; }.portfolio.portfolio-grid#style-43f9542 .portfolio-item .caption .subtitle span { white-space: initial; display: -webkit-box; -webkit-line-clamp: 2; line-clamp: 2; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-43f9542 .portfolio-item .caption .subtitle a, .portfolio.portfolio-grid#style-43f9542 .portfolio-item .caption .subtitle p { white-space: initial; overflow: initial; }.portfolio.portfolio-grid#style-43f9542 .extended-carousel-item .owl-nav .owl-prev div, .portfolio.portfolio-grid#style-43f9542 .extended-carousel-item .owl-nav .owl-next div { color: #ffffff }.portfolio.portfolio-grid#style-43f9542 .extended-carousel-item .owl-nav .owl-prev:hover div, .portfolio.portfolio-grid#style-43f9542 .extended-carousel-item .owl-nav .owl-next:hover div { color: #ffffff }.portfolio.portfolio-grid#style-43f9542 .extended-carousel-item .owl-nav .owl-prev div.position-on, .portfolio.portfolio-grid#style-43f9542 .extended-carousel-item .owl-nav .owl-next div.position-on { background-color: #a07558 }.portfolio.portfolio-grid#style-43f9542 .extended-carousel-item .owl-nav .owl-prev:hover div.position-on, .portfolio.portfolio-grid#style-43f9542 .extended-carousel-item .owl-nav .owl-next:hover div.position-on { background-color: #a07558 }<\/style><style><\/style> <div id=\"style-preloader-43f9542\" class=\"preloader skeleton-carousel\"> <div class=\"skeleton\"> <div class=\"skeleton-posts portfolio-row\"> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18214 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-preloader-wrapper\"> <div class=\"portfolio portfolio-grid extended-portfolio-grid extended-portfolio-carousel extended-carousel-grid no-padding disable-isotope portfolio-style-justified portfolio-style-justified background-style-transparent hover-zooming-blur title-on-hover hover-elements-size-default version-alternative arrows-position-on caption-position-hover loading-animation item-animation-move-up hover-title columns-5 columns-tablet-3 columns-mobile-2 arrows-hover \" id=\"style-43f9542\" data-style-uid=\"43f9542\" data-portfolio-uid=\"grid_a6fb7a0\" data-columns-mobile=\"2\" data-columns-tablet=\"3\" data-columns-desktop=\"5\" data-margin-mobile=\"10\" data-margin-tablet=\"20\" data-margin-desktop=\"25\" data-hover=\"zooming-blur\" data-dots=\"\" data-arrows=\"1\" data-loop=\"\" data-sliding-animation=\"default\" data-autoscroll-speed=\"0\"> <div class=\"portfolio-row-outer \"> <div class=\"portfolio-row clearfix\"> <div class=\"portfolio-set\"> <div class=\"extended-carousel-wrap\"> <div class=\"extended-carousel-item owl-carousel owl-theme owl-loaded\"> <div class=\"owl-stage-outer\"> <div class=\"owl-stage\"> <div class=\"portfolio-item nuevos-lanzamientos ambiental-listado conferenciasimg educacion-listado col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18767 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1768566361\"> <div class=\"wrap clearfix\"> <div class=\"image post-18767 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2026\/01\/seminarioprevencionincendios.jpeg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Seminario de Prevenci\u00f3n de Incendios Forestales &#8211; desde Reserva Elemental Likandes\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/seminario-de-prevencion-de-incendios-forestales\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Seminario de Prevenci\u00f3n de Incendios Forestales &#8211; desde Reserva Elemental Likandes\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos conferenciasimg cop-listado col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18606 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1765395104\"> <div class=\"wrap clearfix\"> <div class=\"image post-18606 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/12\/Portada_Cop_fcs.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"COP30 Brasil &#8211; conferencias 2025 cambio climatico\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/cop30-brasil-conferencia\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"COP30 Brasil &#8211; conferencias 2025 cambio climatico\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos conferenciasimg col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18450 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1759837392\"> <div class=\"wrap clearfix\"> <div class=\"image post-18450 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/10\/Portada_IUCN.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Congreso mundial de la naturaleza de la UICN conferencia abu dabi\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/congreso-mundial-de-la-naturaleza\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Congreso mundial de la naturaleza de la UICN conferencia abu dabi\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos conferencias conferenciasimg col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17022 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1748893842\"> <div class=\"wrap clearfix\"> <div class=\"image post-17022 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Caluga-UNOC3.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Conferencia Tercera Conferencia de las Naciones Unidas sobre los Oc\u00e9anos (UNOC3) mar\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fcs.tv\/tercera-conferencia-de-las-naciones-unidas-sobre-los-oceanos-unoc3\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Conferencia Tercera Conferencia de las Naciones Unidas sobre los Oc\u00e9anos (UNOC3) mar\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos conferencias conferenciasimg monaco-ocean-week-listado col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-16827 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1742647243\"> <div class=\"wrap clearfix\"> <div class=\"image post-16827 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/03\/MOW-2025.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Monaco ocean week Blue Economy Round Table 2025\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/monaco-ocean-week-2025\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Monaco ocean week Blue Economy Round Table 2025\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos conferenciasimg cop-listado cop29 col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-16274 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1730894720\"> <div class=\"wrap clearfix\"> <div class=\"image post-16274 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/11\/welcomeCop29.webp\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"COP29 conferencia Exposici\u00f3n presentaci\u00f3n\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/cop29\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"COP29 conferencia Exposici\u00f3n presentaci\u00f3n\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item nuevos-lanzamientos climate-week-2023-listado conferenciasimg col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-16005 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1726153060\"> <div class=\"wrap clearfix\"> <div class=\"image post-16005 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/09\/Miniatura-NY.jpg\" width=\"340\" height=\"300\" class=\"attachment-full\" alt=\"Agenda FCS-VELUX FONDEN- IUCN en el marco de la cumbre mundial sobre clima\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/agenda-fcs-velux-fonden-iucn-en-el-marco-de-la-cumbre-mundial-sobre-clima\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Agenda FCS-VELUX FONDEN- IUCN en el marco de la cumbre mundial sobre clima\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item conferencias conferenciasimg monaco-ocean-week-listado col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17738 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1712064204\"> <div class=\"wrap clearfix\"> <div class=\"image post-17738 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-General-4.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Monaco Ocean Week 2024 conferencia\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fcs.tv\/monaco-ocean-week-2024\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Monaco Ocean Week 2024 conferencia\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item conferenciasimg cop-listado col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-13714 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1703532512\"> <div class=\"wrap clearfix\"> <div class=\"image post-13714 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/Cop28.jpg\" width=\"340\" height=\"300\" class=\"attachment-full\" alt=\"COP28 conferencia cambio climatico\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/cop28\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"COP28 conferencia cambio climatico\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item climate-week-2023-listado conferenciasimg col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-18024 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1695564116\"> <div class=\"wrap clearfix\"> <div class=\"image post-18024 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/07\/Portada-General-2.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Climate week 2023 Conferencia ONU\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fcs.tv\/climate-week-2023\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Climate week 2023 Conferencia ONU\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item conferenciasimg novopangea-listado col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-13683 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1690312359\"> <div class=\"wrap clearfix\"> <div class=\"image post-13683 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2023\/07\/Portada-General.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"novopangea Colombia 2023\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fcs.tv\/novopangea-colombia-2023\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"novopangea Colombia 2023\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item coedu22-listado conferencias conferenciasimg educacion-listado col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template without-title appearance-type-featured_image post-17367 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1677272776\"> <div class=\"wrap clearfix\"> <div class=\"image post-17367 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2025\/06\/Portada-General-2.jpg\" width=\"733\" height=\"647\" class=\"attachment-full\" alt=\"Conferencia Coedu 22 2023 educaci\u00f3n\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"\/coedu22-2023\/\" target=\"_self\" class=\"icon inner-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Conferencia Coedu 22 2023 educaci\u00f3n\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div><!-- .portflio-set --> <\/div><!-- .row--> <div class=\"slider-prev-icon position-on\"> <i class=\"default\"><\/i> <\/div> <div class=\"slider-next-icon position-on\"> <i class=\"default\"><\/i> <\/div> <\/div><!-- .full-width --> <\/div><!-- .portfolio--> <\/div><!-- .portfolio-preloader-wrapper-->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1715872249716{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;background-color: #212128 !important;}&#8221; el_class=&#8221;gridcarousel&#8221;][vc_column css=&#8221;.vc_custom_1715872242318{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1720669469378{margin-top: 0px !important;margin-bottom: 0px !important;padding-bottom: 30px !important;}&#8221; css_animation=&#8221;fadeInUp&#8221;]<\/p>\n<h3 style=\"text-align: center;\"><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/der.png\" \/><span class=\"categoriatitulo\">RECURSOS DIGITALES RELACIONADOS<\/span><img class=\"hojas\" src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2024\/06\/izq.png\" \/><\/h3>\n<p>[\/vc_column_text]<style>.portfolio.portfolio-grid#style-353b566:not(.inited) .portfolio-item, .preloader#style-preloader-353b566 .portfolio-item { padding: calc(25px\/2) !important; }.portfolio.portfolio-grid#style-353b566:not(.inited) .owl-stage, .preloader#style-preloader-353b566 .skeleton-posts.portfolio-row { margin: calc(-25px\/2); }.portfolio.portfolio-grid#style-353b566 .fullwidth-block:not(.no-paddings) { padding-left: 25px; padding-right: 25px; }.portfolio.portfolio-grid#style-353b566.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(25px\/2) !important; margin: calc(-25px\/2); }@media (max-width: 991px) { .portfolio.portfolio-grid#style-353b566:not(.inited) .portfolio-item, .preloader#style-preloader-353b566 .portfolio-item { padding: calc(20px\/2) !important; }.portfolio.portfolio-grid#style-353b566:not(.inited) .owl-stage, .preloader#style-preloader-353b566 .skeleton-posts.portfolio-row { margin: calc(-20px\/2); }.portfolio.portfolio-grid#style-353b566 .fullwidth-block:not(.no-paddings) { padding-left: 20px; padding-right: 20px; }.portfolio.portfolio-grid#style-353b566.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(20px\/2) !important; margin: calc(-20px\/2); }}@media (max-width: 767px) { .portfolio.portfolio-grid#style-353b566:not(.inited) .portfolio-item, .preloader#style-preloader-353b566 .portfolio-item { padding: calc(10px\/2) !important; }.portfolio.portfolio-grid#style-353b566:not(.inited) .owl-stage, .preloader#style-preloader-353b566 .skeleton-posts.portfolio-row { margin: calc(-10px\/2); }.portfolio.portfolio-grid#style-353b566 .fullwidth-block:not(.no-paddings) { padding-left: 10px; padding-right: 10px; }.portfolio.portfolio-grid#style-353b566.has-shadowed-items .owl-carousel .owl-stage-outer { padding: calc(10px\/2) !important; margin: calc(-10px\/2); }}.portfolio.portfolio-grid#style-353b566 .portfolio-item:not(.custom-ratio, .double-item) .image-inner:not(.empty) { aspect-ratio: 1.1 !important; height: auto; }.portfolio.portfolio-grid#style-353b566 .portfolio-item .caption .title span { letter-spacing: px !important; }.portfolio.portfolio-grid#style-353b566 .portfolio-item .caption .title span { white-space: initial; max-height: initial; display: -webkit-box; -webkit-line-clamp: 4; line-clamp: 4; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-353b566 .portfolio-item .caption .subtitle { max-height: initial !important; }.portfolio.portfolio-grid#style-353b566 .portfolio-item .caption .subtitle span { white-space: initial; display: -webkit-box; -webkit-line-clamp: 2; line-clamp: 2; -webkit-box-orient: vertical; }.portfolio.portfolio-grid#style-353b566 .portfolio-item .caption .subtitle a, .portfolio.portfolio-grid#style-353b566 .portfolio-item .caption .subtitle p { white-space: initial; overflow: initial; }.portfolio.portfolio-grid#style-353b566 .extended-carousel-item .owl-nav .owl-prev div, .portfolio.portfolio-grid#style-353b566 .extended-carousel-item .owl-nav .owl-next div { color: #ffffff }.portfolio.portfolio-grid#style-353b566 .extended-carousel-item .owl-nav .owl-prev:hover div, .portfolio.portfolio-grid#style-353b566 .extended-carousel-item .owl-nav .owl-next:hover div { color: #ffffff }.portfolio.portfolio-grid#style-353b566 .extended-carousel-item .owl-nav .owl-prev div.position-on, .portfolio.portfolio-grid#style-353b566 .extended-carousel-item .owl-nav .owl-next div.position-on { background-color: #a07558 }.portfolio.portfolio-grid#style-353b566 .extended-carousel-item .owl-nav .owl-prev:hover div.position-on, .portfolio.portfolio-grid#style-353b566 .extended-carousel-item .owl-nav .owl-next:hover div.position-on { background-color: #a07558 }<\/style><style><\/style> <div id=\"style-preloader-353b566\" class=\"preloader skeleton-carousel\"> <div class=\"skeleton\"> <div class=\"skeleton-posts portfolio-row\"> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-17367 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-17367 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-17367 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <div class=\"portfolio-item col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-17367 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-preloader-wrapper\"> <div class=\"portfolio portfolio-grid extended-portfolio-grid extended-portfolio-carousel extended-carousel-grid no-padding disable-isotope portfolio-style-justified portfolio-style-justified background-style-transparent hover-zooming-blur title-on-hover hover-elements-size-default version-alternative arrows-position-on caption-position-hover loading-animation item-animation-move-up hover-title columns-5 columns-tablet-3 columns-mobile-2 arrows-hover \" id=\"style-353b566\" data-style-uid=\"353b566\" data-portfolio-uid=\"grid_a6fb7a0\" data-columns-mobile=\"2\" data-columns-tablet=\"3\" data-columns-desktop=\"5\" data-margin-mobile=\"10\" data-margin-tablet=\"20\" data-margin-desktop=\"25\" data-hover=\"zooming-blur\" data-dots=\"\" data-arrows=\"1\" data-loop=\"\" data-sliding-animation=\"default\" data-autoscroll-speed=\"0\"> <div class=\"portfolio-row-outer \"> <div class=\"portfolio-row clearfix\"> <div class=\"portfolio-set\"> <div class=\"extended-carousel-wrap\"> <div class=\"extended-carousel-item owl-carousel owl-theme owl-loaded\"> <div class=\"owl-stage-outer\"> <div class=\"owl-stage\"> <div class=\"portfolio-item biblioteca-cambio-climatico col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-4598 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1648722463\"> <div class=\"wrap clearfix\"> <div class=\"image post-4598 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2022\/03\/Conservacion-del-medio-ambiente.jpg\" width=\"709\" height=\"625\" class=\"attachment-full\" alt=\"Conservaci\u00f3n del medio Ambiente y Salud Humana\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fundacionmeri.cl\/wp-content\/uploads\/2020\/09\/conservacion-y-salud-1.pdf\" target=\"_blank\" class=\"icon outer-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Conservaci\u00f3n del medio Ambiente y Salud Humana\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"title \"> <span class=\"title-h5 \"> Conservaci\u00f3n del medio Ambiente y Salud Humana <\/span> <\/div> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item biblioteca-cambio-climatico col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-4596 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1648722207\"> <div class=\"wrap clearfix\"> <div class=\"image post-4596 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2022\/03\/Lasballenasazules.jpg\" width=\"709\" height=\"625\" class=\"attachment-full\" alt=\"Las Ballenas Azules y otros cet\u00e1ceos en la Patagonia Norte\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/reservaelemental.cl\/wp-content\/uploads\/2020\/07\/lasballenas-azules-cap2.pdf\" target=\"_blank\" class=\"icon outer-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Las Ballenas Azules y otros cet\u00e1ceos en la Patagonia Norte\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"title \"> <span class=\"title-h5 \"> Las Ballenas Azules y otros cet\u00e1ceos en la Patagonia Norte <\/span> <\/div> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item biblioteca-cambio-climatico col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-4476 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1648143427\"> <div class=\"wrap clearfix\"> <div class=\"image post-4476 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2022\/03\/Conservacion-Efectiva.jpg\" width=\"709\" height=\"625\" class=\"attachment-full\" alt=\"Conservaci\u00f3n Efectiva: Abordaje Territorial\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/reservaelemental.cl\/wp-content\/uploads\/2021\/08\/Conservacio%CC%81n-efectiva.pdf\" target=\"_blank\" class=\"icon outer-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Conservaci\u00f3n Efectiva: Abordaje Territorial\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"title \"> <span class=\"title-h5 \"> Conservaci\u00f3n Efectiva: Abordaje Territorial <\/span> <\/div> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item biblioteca-cambio-climatico col-xs-6 col-sm-4 columns-desktop-5 owl-item item-animations-not-inited portfolio-item-template appearance-type-featured_image post-4470 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" data-default-sort=\"0\" data-sort-date=\"1648142671\"> <div class=\"wrap clearfix\"> <div class=\"image post-4470 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner \"> <picture> <img src=\"https:\/\/fcs.tv\/wp-content\/uploads\/2022\/03\/Modelo-de-conservacion.jpg\" width=\"709\" height=\"625\" class=\"attachment-full\" alt=\"Conservaci\u00f3n efectiva para un desarrollo sostenible\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/fundacionmeri.cl\/wp-content\/uploads\/2021\/01\/Reserva-Elemental_Libro-Conservacio%CC%81n-Efectiva.pdf\" target=\"_blank\" class=\"icon outer-link \" data-elementor-open-lightbox=\"no\" aria-label=\"Conservaci\u00f3n efectiva para un desarrollo sostenible\"> <i class=\"default\"><\/i> <\/a> <\/div> <div class=\"caption\"> <div class=\"title \"> <span class=\"title-h5 \"> Conservaci\u00f3n efectiva para un desarrollo sostenible <\/span> <\/div> <div class=\"description\"> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div><!-- .portflio-set --> <\/div><!-- .row--> <div class=\"slider-prev-icon position-on\"> <i class=\"default\"><\/i> <\/div> <div class=\"slider-next-icon position-on\"> <i class=\"default\"><\/i> <\/div> <\/div><!-- .full-width --> <\/div><!-- .portfolio--> <\/div><!-- .portfolio-preloader-wrapper-->[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content&#8221; content_placement=&#8221;middle&#8221; css_animation=&#8221;none&#8221; tablet_padding_left=&#8221;0&#8243; tablet_padding_right=&#8221;0&#8243; tablet_margin_left=&#8221;0&#8243; tablet_margin_right=&#8221;0&#8243; mobile_padding_left=&#8221;0&#8243; mobile_padding_right=&#8221;0&#8243; mobile_margin_left=&#8221;0&#8243; mobile_margin_right=&#8221;0&#8243;][vc_column css=&#8221;.vc_custom_1721048756342{margin-right: 40px !important;margin-left: 40px !important;}&#8221; tablet_padding_left=&#8221;0&#8243; tablet_padding_right=&#8221;0&#8243; tablet_margin_left=&#8221;0&#8243;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":18193,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-18191","page","type-page","status-publish","has-post-thumbnail"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["es","en"],"languages":{"es":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/pages\/18191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/comments?post=18191"}],"version-history":[{"count":3,"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/pages\/18191\/revisions"}],"predecessor-version":[{"id":18196,"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/pages\/18191\/revisions\/18196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/media\/18193"}],"wp:attachment":[{"href":"https:\/\/fcs.tv\/en\/wp-json\/wp\/v2\/media?parent=18191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}